{"id":748,"date":"2023-12-02T01:41:59","date_gmt":"2023-12-02T04:41:59","guid":{"rendered":"https:\/\/ejezeta.org\/bot\/?post_type=product&#038;p=748"},"modified":"2024-10-18T10:45:50","modified_gmt":"2024-10-18T13:45:50","slug":"tateti-3d","status":"publish","type":"product","link":"https:\/\/ejezeta.org\/bot\/producto\/tateti-3d\/","title":{"rendered":"TaTeTi 3D"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":749,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[18,57,72],"product_tag":[75,74,73],"class_list":{"0":"post-748","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-sin-categorizar","7":"product_cat-bot","8":"product_cat-juegos-ingenio","9":"product_tag-3d","10":"product_tag-ingenio","11":"product_tag-juegos","13":"first","14":"instock","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TaTeTi 3D &#8212; BOT - Rob\u00f3tica Educativa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ejezeta.org\/bot\/producto\/tateti-3d\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TaTeTi 3D &#8212; BOT - Rob\u00f3tica Educativa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ejezeta.org\/bot\/producto\/tateti-3d\/\" \/>\n<meta property=\"og:site_name\" content=\"BOT - Rob\u00f3tica Educativa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/roboticaeducativamza\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-18T13:45:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ejezeta.org\/bot\/wp-content\/uploads\/2023\/12\/BOT-Tienda-5.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@roboticaeducativamza\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ejezeta.org\/bot\/producto\/tateti-3d\/\",\"url\":\"https:\/\/ejezeta.org\/bot\/producto\/tateti-3d\/\",\"name\":\"TaTeTi 3D &#8212; BOT - Rob\u00f3tica Educativa\",\"isPartOf\":{\"@id\":\"https:\/\/ejezeta.org\/bot\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ejezeta.org\/bot\/producto\/tateti-3d\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ejezeta.org\/bot\/producto\/tateti-3d\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ejezeta.org\/bot\/wp-content\/uploads\/2023\/12\/BOT-Tienda-5.png\",\"datePublished\":\"2023-12-02T04:41:59+00:00\",\"dateModified\":\"2024-10-18T13:45:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ejezeta.org\/bot\/producto\/tateti-3d\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ejezeta.org\/bot\/producto\/tateti-3d\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ejezeta.org\/bot\/producto\/tateti-3d\/#primaryimage\",\"url\":\"https:\/\/ejezeta.org\/bot\/wp-content\/uploads\/2023\/12\/BOT-Tienda-5.png\",\"contentUrl\":\"https:\/\/ejezeta.org\/bot\/wp-content\/uploads\/2023\/12\/BOT-Tienda-5.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ejezeta.org\/bot\/producto\/tateti-3d\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/ejezeta.org\/bot\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda de Productos de Electr\u00f3nica\",\"item\":\"https:\/\/ejezeta.org\/bot\/tienda-electronica\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"TaTeTi 3D\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ejezeta.org\/bot\/#website\",\"url\":\"https:\/\/ejezeta.org\/bot\/\",\"name\":\"BOT - Rob\u00f3tica Educativa\",\"description\":\"Laboratorio de Rob\u00f3tica\",\"publisher\":{\"@id\":\"https:\/\/ejezeta.org\/bot\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ejezeta.org\/bot\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ejezeta.org\/bot\/#organization\",\"name\":\"Eje Zeta\",\"url\":\"https:\/\/ejezeta.org\/bot\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ejezeta.org\/bot\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ejezeta.org\/bot\/wp-content\/uploads\/2019\/08\/BOT_marca_sin_fondo.png\",\"contentUrl\":\"https:\/\/ejezeta.org\/bot\/wp-content\/uploads\/2019\/08\/BOT_marca_sin_fondo.png\",\"width\":1047,\"height\":617,\"caption\":\"Eje Zeta\"},\"image\":{\"@id\":\"https:\/\/ejezeta.org\/bot\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/roboticaeducativamza\",\"https:\/\/x.com\/roboticaeducativamza\",\"https:\/\/www.instagram.com\/roboticaeducativamza\/\",\"https:\/\/www.youtube.com\/channel\/UCqDYebO8TxeHNlCKOvwnqaw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TaTeTi 3D &#8212; BOT - Rob\u00f3tica Educativa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ejezeta.org\/bot\/producto\/tateti-3d\/","og_locale":"es_ES","og_type":"article","og_title":"TaTeTi 3D &#8212; BOT - Rob\u00f3tica Educativa","og_url":"https:\/\/ejezeta.org\/bot\/producto\/tateti-3d\/","og_site_name":"BOT - Rob\u00f3tica Educativa","article_publisher":"https:\/\/www.facebook.com\/roboticaeducativamza","article_modified_time":"2024-10-18T13:45:50+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/ejezeta.org\/bot\/wp-content\/uploads\/2023\/12\/BOT-Tienda-5.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@roboticaeducativamza","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ejezeta.org\/bot\/producto\/tateti-3d\/","url":"https:\/\/ejezeta.org\/bot\/producto\/tateti-3d\/","name":"TaTeTi 3D &#8212; BOT - Rob\u00f3tica Educativa","isPartOf":{"@id":"https:\/\/ejezeta.org\/bot\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ejezeta.org\/bot\/producto\/tateti-3d\/#primaryimage"},"image":{"@id":"https:\/\/ejezeta.org\/bot\/producto\/tateti-3d\/#primaryimage"},"thumbnailUrl":"https:\/\/ejezeta.org\/bot\/wp-content\/uploads\/2023\/12\/BOT-Tienda-5.png","datePublished":"2023-12-02T04:41:59+00:00","dateModified":"2024-10-18T13:45:50+00:00","breadcrumb":{"@id":"https:\/\/ejezeta.org\/bot\/producto\/tateti-3d\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ejezeta.org\/bot\/producto\/tateti-3d\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ejezeta.org\/bot\/producto\/tateti-3d\/#primaryimage","url":"https:\/\/ejezeta.org\/bot\/wp-content\/uploads\/2023\/12\/BOT-Tienda-5.png","contentUrl":"https:\/\/ejezeta.org\/bot\/wp-content\/uploads\/2023\/12\/BOT-Tienda-5.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/ejezeta.org\/bot\/producto\/tateti-3d\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ejezeta.org\/bot\/"},{"@type":"ListItem","position":2,"name":"Tienda de Productos de Electr\u00f3nica","item":"https:\/\/ejezeta.org\/bot\/tienda-electronica\/"},{"@type":"ListItem","position":3,"name":"TaTeTi 3D"}]},{"@type":"WebSite","@id":"https:\/\/ejezeta.org\/bot\/#website","url":"https:\/\/ejezeta.org\/bot\/","name":"BOT - Rob\u00f3tica Educativa","description":"Laboratorio de Rob\u00f3tica","publisher":{"@id":"https:\/\/ejezeta.org\/bot\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ejezeta.org\/bot\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/ejezeta.org\/bot\/#organization","name":"Eje Zeta","url":"https:\/\/ejezeta.org\/bot\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ejezeta.org\/bot\/#\/schema\/logo\/image\/","url":"https:\/\/ejezeta.org\/bot\/wp-content\/uploads\/2019\/08\/BOT_marca_sin_fondo.png","contentUrl":"https:\/\/ejezeta.org\/bot\/wp-content\/uploads\/2019\/08\/BOT_marca_sin_fondo.png","width":1047,"height":617,"caption":"Eje Zeta"},"image":{"@id":"https:\/\/ejezeta.org\/bot\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/roboticaeducativamza","https:\/\/x.com\/roboticaeducativamza","https:\/\/www.instagram.com\/roboticaeducativamza\/","https:\/\/www.youtube.com\/channel\/UCqDYebO8TxeHNlCKOvwnqaw"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ejezeta.org\/bot\/wp-json\/wp\/v2\/product\/748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ejezeta.org\/bot\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ejezeta.org\/bot\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ejezeta.org\/bot\/wp-json\/wp\/v2\/comments?post=748"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ejezeta.org\/bot\/wp-json\/wp\/v2\/media\/749"}],"wp:attachment":[{"href":"https:\/\/ejezeta.org\/bot\/wp-json\/wp\/v2\/media?parent=748"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ejezeta.org\/bot\/wp-json\/wp\/v2\/product_brand?post=748"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ejezeta.org\/bot\/wp-json\/wp\/v2\/product_cat?post=748"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ejezeta.org\/bot\/wp-json\/wp\/v2\/product_tag?post=748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}